{"id":71497,"date":"2023-05-15T14:26:54","date_gmt":"2023-05-15T12:26:54","guid":{"rendered":"https:\/\/biblekids.io\/?p=71497"},"modified":"2024-11-30T19:58:32","modified_gmt":"2024-11-30T18:58:32","slug":"der-barmherzige-samariter","status":"publish","type":"post","link":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/","title":{"rendered":"Der barmherzige Samariter"},"content":{"rendered":"\n\n\t<section class=\"section\" id=\"section_1288680665\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1894012551\">\n\n\n\t<div id=\"col-885399404\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3>Jesus will uns Barmherzigkeit lehren<\/h3>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-859030527\">\n\n\n\t<div id=\"col-1253950753\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"lead\" style=\"font-weight: 400;\">&nbsp;<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71531 alignleft\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_poster-Jesus_Den_Barmhjertige_Samaritan2-711x400.jpg\" alt=\"\" width=\"500\" height=\"281\">Seinen N\u00e4chsten wie sich selbst zu lieben bedeutet, dass wir uns um das Wohlergehen anderer genauso k\u00fcmmern, wie um unser eigenes. In dieser Geschichte m\u00f6chte Jesus uns lehren, wie wichtig es ist f\u00fcrsorglich und gut zu allen Menschen zu sein, nicht nur zu denen, die wir gerne m\u00f6gen. Das ist es, was Jesus von uns will.   <\/p>\n<p class=\"lead\" style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Dieses Thema ist f\u00fcr Kinder in der Zielgruppe leicht verst\u00e4ndlich, wenn sie den Film gesehen haben. Man kann mit den Kindern dar\u00fcber sprechen, was sie gesehen haben und sie in eigenen Worten erz\u00e4hlen lassen, was sie aus dem Gleichnis gelernt haben. Dadurch werden sie sich besser daran erinnern und k\u00f6nnen es in ihrem eigenen Leben anwenden. <\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-90581135\">\n\n\n\t<div id=\"col-1032051086\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3>Bereit zu sein einander zu helfen<\/h3>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-776093105\">\n\n\n\t<div id=\"col-1990725265\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"lead\" style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71561 alignright\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_poster-Jesus_Den_Barmhjertige_Samaritan4-711x400.jpg\" alt=\"\" width=\"500\" height=\"281\"><\/p>\n<p class=\"lead\" style=\"font-weight: 400;\">In dem Film treffen wir Simon, der h\u00f6rt, wie Jesus das Gleichnis vom barmherzigen Samariter erz\u00e4hlt. Er ist so begeistert von der Geschichte, dass er nach Hause l\u00e4uft und das Geh\u00f6rte an Sarah und seine Mama weitergibt. <\/p>\n<p class=\"lead\" style=\"font-weight: 400;\">Jesus erz\u00e4hlt von einem j\u00fcdischen Mann, der auf Reisen ist. Pl\u00f6tzlich wird er von R\u00e4ubern \u00fcberfallen und liegt schlie\u00dflich niedergeschlagen und verletzt am Boden. Danach kommen sowohl ein Levit als auch ein Priester&nbsp;, beides damals wichtige Leute, die viel \u00fcber Gott wissen sollten, aber keiner von ihnen h\u00e4lt an und hilft dem Verletzten. Zum Schluss kommt ein Samariter, und Simon wei\u00df, dass die Leute dieses Volkes nicht gerade die besten Freunde der Juden sind. Trotzdem entscheidet sich der Samariter dazu, &nbsp;G\u00fcte und F\u00fcrsorge zu zeigen. Er hilft dem Mann, verbindet seine Wunden und nimmt ihn mit an einen Ort, wo er bleiben kann, bis es ihm besser geht.    <\/p>\n<p class=\"lead\" style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71516 alignleft\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_poster-Jesus_Den_Barmhjertige_Samaritan-711x400.jpg\" alt=\"\" width=\"500\" height=\"281\">Das k\u00f6nnen die Kinder auch in ihrem eigenen Leben machen. Es geht darum zu erkennen, wie es anderen geht und denjenigen zu helfen, die es brauchen. Kannst du als Mentor ein Gespr\u00e4ch mit den Kindern dar\u00fcber beginnen? Die vorgeschlagenen Fragen k\u00f6nnen helfen, ein solches Gespr\u00e4ch in Gang zu bringen.  <\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-650760914\">\n\n\n\t<div id=\"col-2114853397\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h4>Fragen f\u00fcr ein Gespr\u00e4ch<\/h4>\n<p class=\"lead\">Wisst ihr, was Barmherzigkeit ist?<\/p>\n<p class=\"lead\">Was hat der Samariter richtig gemacht?<\/p>\n<p class=\"lead\"><span style=\"font-weight: 400;\">Wie k\u00f6nnen wir anderen Menschen Barmherzigkeit erweisen?<\/span><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-122212038\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h4>Passende Lieder zum Thema<\/h4>\n<p class=\"lead\">MB 220 &#8211; Eins ich wei\u00df<\/p>\n<p class=\"lead\">MB 35 &#8211; Es steht in Gottes heilgem Wort<\/p>\n<p class=\"lead\">MB 203 &#8211; Lieber Heiland, ich bin klein<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-144937264\">\n\n\n\t<div id=\"col-216384884\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3>Passende Bibelverse zum Thema<\/h3>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1078963150\">\n\n\n\t<div id=\"col-938778366\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<blockquote>\n<p style=\"font-weight: 400;\">Denn das ganze Gesetz ist in dem einen Wort erf\u00fcllt:&nbsp; <em>Liebe deinen N\u00e4chsten wie dich selbst!<\/em> &nbsp;Gal. 5, 14<\/p>\n<\/blockquote>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1594881627\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<blockquote>\n<p style=\"font-weight: 400;\">Alles nun, was ihr wollt, dass euch die Leute tun sollen, das tut ihr ihnen auch! &nbsp;Mat. 7, 12<\/p>\n<\/blockquote>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-918736432\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<blockquote>\n<p style=\"font-weight: 400;\">Selig sind die Barmherzigen, denn sie werden Barmherzigkeit erlangen. &nbsp;Mat. 5, 7 <\/p>\n<\/blockquote>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1288680665 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(247, 247, 247);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<p>In der Geschichte \u00fcber den barmherzigen Samariter m\u00f6chte Jesus uns lehren, wie wichtig es ist f\u00fcrsorglich und gut zu allen Menschen zu sein.<\/p>\n","protected":false},"author":9614,"featured_media":72156,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"bcc_login_visibility":1,"bcc_groups":[],"bcc_groups_email":true,"bcc_visibility_groups":[],"bcc_visibility_groups_email":false,"sent_notifications":[],"footnotes":"","_links_to":"","_links_to_target":""},"categories":[163,128],"tags":[],"class_list":["post-71497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3-5-jahre","category-themenseiten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der barmherzige Samariter \u2013 Bibelgeschichte f\u00fcr die Kleinsten<\/title>\n<meta name=\"description\" content=\"In der Geschichte \u00fcber den barmherzigen Samariter m\u00f6chte Jesus uns lehren, wie wichtig es ist f\u00fcrsorglich und gut zu allen Menschen zu sein. Materialien f\u00fcr den Gottesdienst der kleinen Kinder\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der barmherzige Samariter \u2013 Bibelgeschichte f\u00fcr die Kleinsten\" \/>\n<meta property=\"og:description\" content=\"In der Geschichte \u00fcber den barmherzigen Samariter m\u00f6chte Jesus uns lehren, wie wichtig es ist f\u00fcrsorglich und gut zu allen Menschen zu sein. Materialien f\u00fcr den Gottesdienst der kleinen Kinder\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/\" \/>\n<meta property=\"og:site_name\" content=\"Bible Kids\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-15T12:26:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-30T18:58:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"15974\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"15974\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/der-barmherzige-samariter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/der-barmherzige-samariter\\\/\"},\"author\":{\"name\":\"15974\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\"},\"headline\":\"Der barmherzige Samariter\",\"datePublished\":\"2023-05-15T12:26:54+00:00\",\"dateModified\":\"2024-11-30T18:58:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/der-barmherzige-samariter\\\/\"},\"wordCount\":518,\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/der-barmherzige-samariter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png\",\"articleSection\":[\"3-5 Jahre\",\"Themenseiten\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/der-barmherzige-samariter\\\/\",\"url\":\"https:\\\/\\\/biblekids.io\\\/de\\\/der-barmherzige-samariter\\\/\",\"name\":\"Der barmherzige Samariter \u2013 Bibelgeschichte f\u00fcr die Kleinsten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/der-barmherzige-samariter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/der-barmherzige-samariter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png\",\"datePublished\":\"2023-05-15T12:26:54+00:00\",\"dateModified\":\"2024-11-30T18:58:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\"},\"description\":\"In der Geschichte \u00fcber den barmherzigen Samariter m\u00f6chte Jesus uns lehren, wie wichtig es ist f\u00fcrsorglich und gut zu allen Menschen zu sein. Materialien f\u00fcr den Gottesdienst der kleinen Kinder\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/der-barmherzige-samariter\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biblekids.io\\\/de\\\/der-barmherzige-samariter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/der-barmherzige-samariter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png\",\"contentUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/der-barmherzige-samariter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/biblekids.io\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der barmherzige Samariter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\",\"url\":\"https:\\\/\\\/biblekids.io\\\/no\\\/\",\"name\":\"Bible Kids\",\"description\":\"Bibelgeschichten f\u00fcr Kinder\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biblekids.io\\\/no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\",\"name\":\"15974\",\"url\":\"https:\\\/\\\/biblekids.io\\\/de\\\/author\\\/15974\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der barmherzige Samariter \u2013 Bibelgeschichte f\u00fcr die Kleinsten","description":"In der Geschichte \u00fcber den barmherzigen Samariter m\u00f6chte Jesus uns lehren, wie wichtig es ist f\u00fcrsorglich und gut zu allen Menschen zu sein. Materialien f\u00fcr den Gottesdienst der kleinen Kinder","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/","og_locale":"de_DE","og_type":"article","og_title":"Der barmherzige Samariter \u2013 Bibelgeschichte f\u00fcr die Kleinsten","og_description":"In der Geschichte \u00fcber den barmherzigen Samariter m\u00f6chte Jesus uns lehren, wie wichtig es ist f\u00fcrsorglich und gut zu allen Menschen zu sein. Materialien f\u00fcr den Gottesdienst der kleinen Kinder","og_url":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/","og_site_name":"Bible Kids","article_published_time":"2023-05-15T12:26:54+00:00","article_modified_time":"2024-11-30T18:58:32+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png","type":"image\/png"}],"author":"15974","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"15974","Gesch\u00e4tzte Lesezeit":"4 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/#article","isPartOf":{"@id":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/"},"author":{"name":"15974","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22"},"headline":"Der barmherzige Samariter","datePublished":"2023-05-15T12:26:54+00:00","dateModified":"2024-11-30T18:58:32+00:00","mainEntityOfPage":{"@id":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/"},"wordCount":518,"image":{"@id":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png","articleSection":["3-5 Jahre","Themenseiten"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/","url":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/","name":"Der barmherzige Samariter \u2013 Bibelgeschichte f\u00fcr die Kleinsten","isPartOf":{"@id":"https:\/\/biblekids.io\/no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/#primaryimage"},"image":{"@id":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png","datePublished":"2023-05-15T12:26:54+00:00","dateModified":"2024-11-30T18:58:32+00:00","author":{"@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22"},"description":"In der Geschichte \u00fcber den barmherzigen Samariter m\u00f6chte Jesus uns lehren, wie wichtig es ist f\u00fcrsorglich und gut zu allen Menschen zu sein. Materialien f\u00fcr den Gottesdienst der kleinen Kinder","breadcrumb":{"@id":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/#primaryimage","url":"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png","contentUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/biblekids.io\/de\/der-barmherzige-samariter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/biblekids.io\/ru\/"},{"@type":"ListItem","position":2,"name":"Der barmherzige Samariter"}]},{"@type":"WebSite","@id":"https:\/\/biblekids.io\/no\/#website","url":"https:\/\/biblekids.io\/no\/","name":"Bible Kids","description":"Bibelgeschichten f\u00fcr Kinder","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biblekids.io\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22","name":"15974","url":"https:\/\/biblekids.io\/de\/author\/15974\/"}]}},"_links":{"self":[{"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/posts\/71497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/users\/9614"}],"replies":[{"embeddable":true,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/comments?post=71497"}],"version-history":[{"count":17,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/posts\/71497\/revisions"}],"predecessor-version":[{"id":82183,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/posts\/71497\/revisions\/82183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/media\/72156"}],"wp:attachment":[{"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/media?parent=71497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/categories?post=71497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/tags?post=71497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}