{"id":84203,"date":"2023-11-29T10:24:25","date_gmt":"2023-11-29T09:24:25","guid":{"rendered":"https:\/\/biblekids.io\/?p=84203"},"modified":"2024-11-30T20:12:40","modified_gmt":"2024-11-30T19:12:40","slug":"die-reise-zum-anfang-eine-weihnachtsgeschichte","status":"publish","type":"post","link":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/","title":{"rendered":"Die Reise zum Anfang &#8211; eine Weihnachtsgeschichte"},"content":{"rendered":"\n\n\t<section class=\"section\" id=\"section_794199080\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1523952856\">\n\n\n\t<div id=\"col-985169664\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><span class=\"TextRun SCXW75953993 BCX4\" lang=\"NB-NO\" xml:lang=\"NB-NO\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW75953993 BCX4\" data-ccp-parastyle=\"heading 3\">Eine neue Hoffnung f\u00fcr die Menschen<\/span><\/span><span class=\"EOP SCXW75953993 BCX4\" data-ccp-props=\"{\"134233117\":true,\"134233118\":true,\"134245418\":true,\"134245529\":true,\"201341983\":0,\"335559740\":259}\">&nbsp;<\/span><\/h3>\n<p class=\"lead\" style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-84388 alignleft\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/11\/poster-VX-399990-10-10-24-00-711x400.jpg\" alt=\"\" width=\"500\" height=\"281\">Die Reise zum Anfang ist die Geschichte des Weihnachtsevangeliums, \u00fcber den Besuch des Engels Gabriel bei Maria, \u00fcber die anstrengende Reise nach Bethlehem und alles, was bei der Geburt Jesu passierte. Aber auch \u00fcber den machthungrigen Herodes, die drei Weisen und die Hirten auf dem Feld.&nbsp;<\/p>\n<p class=\"lead\" style=\"font-weight: 400;\">Dass Jesus auf die Erde kam, markiert den Beginn einer ganz neuen M\u00f6glichkeit f\u00fcr die Menschheit. Jesus sah, dass die Menschen nicht immer freundlich zueinander sein oder so leben konnten, wie Gott es von ihnen wollte. Sie litten und hatten viele Probleme. Er wollte uns so gerne helfen, deshalb kam er auf die Erde. Er gab seine ganze Herrlichkeit im Himmel auf und wurde als &nbsp;Mensch wie wir in diese Welt geboren. Um uns von unseren S\u00fcnden zu erl\u00f6sen und uns ewige Hoffnung zu geben.&nbsp;&nbsp;<\/p>\n<h3><span class=\"TextRun SCXW219184592 BCX4\" lang=\"NB-NO\" xml:lang=\"NB-NO\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW219184592 BCX4\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-43108 alignright\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/Film_Poster_NATI_v2-320x400.jpg\" alt=\"\" width=\"320\" height=\"400\">Eigenproduzierte Animationsserie<\/span><\/span><span class=\"EOP SCXW219184592 BCX4\" data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559740\":240}\">&nbsp;<\/span><\/h3>\n<p class=\"lead\"><span data-contrast=\"none\">Die Animationsserie &#8222;Die Reise zum Anfang\u201c wird ausschlie\u00dflich von BCC Media produziert. Sie wurde mit unseren eigenen Kapazit\u00e4ten geschrieben, gezeichnet und animiert. Unsere Vision war es, eine Serie zu schaffen, die Kinder anspricht und Freude, Dankbarkeit und Aufregung erzeugt \u00fcber die Geschehnisse in der kleinen Stadt Bethlehem vor mehr als 2000 Jahren.<\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559740\":240}\">&nbsp;<\/span><\/p>\n<p class=\"lead\"><span data-contrast=\"none\">Die Serie ist in drei Teile gegliedert, aber auch als 15-min\u00fctiger Film zusammengefasst. So kann die Serie in drei Teile aufgeteilt werden, zum Beispiel in den Kindergottesdiensten vor Weihnachten, oder als ganzer Film angesehen werden.<\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559740\":240}\">&nbsp;<\/span><\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-64705\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2022\/05\/film.png\" alt=\"\" width=\"40\" height=\"40\">&nbsp;Erster Teil der Reise<\/h3>\n<p class=\"lead\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-43075\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/Skjermbilde-2020-11-23-kl.-15.24.02-709x400.png\" alt=\"\" width=\"500\" height=\"282\">In der ersten Folge h\u00f6ren wir die Geschichte, als der Engel Maria besuchte und ihr sagte, dass sie einen Sohn zur Welt bringen w\u00fcrde, der Gottes Sohn und der Retter der Welt sein w\u00fcrde. Ihren Verlobten Josef besuchte der Engel ebenfalls. Er wollte Maria und das kleine Kind gerne unterst\u00fctzen.<\/p>\n<p class=\"lead\">Als Maria kurz vor der Geburt stand, beschloss K\u00f6nig Herodes, dass alle Einwohner Israels in einer Volksz\u00e4hlung erfasst werden sollten, und jeder musste in die Stadt gehen, aus der er urspr\u00fcnglich stammte. Maria und Josef mussten in die Stadt Bethlehem ziehen, um dort registriert zu werden.<\/p>\n<p class=\"lead\">Zur gleichen Zeit entdeckten drei weise M\u00e4nner in einem fernen Land einen neuen Stern am Himmel. Sie wussten, dass dies bedeutete, dass ein neuer K\u00f6nig geboren werden w\u00fcrde, und sie machten sich auf den Weg, um ihn zu ehren.<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-64705\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2022\/05\/film.png\" alt=\"\" width=\"40\" height=\"40\">&nbsp;Zweiter Teil der Reise<\/h3>\n<p class=\"lead\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-84405\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/11\/6500@PAL.jpeg\" alt=\"\" width=\"300\" height=\"169\">In dieser Folge erfahren wir, was geschah, als Maria und Josef in Bethlehem ankamen. In der Stadt waren schon so viele Menschen, dass sie keinen Schlafplatz finden konnten. Schlie\u00dflich schliefen sie in einem Stall. Und hier in diesem Stall wurde der Retter der Welt geboren.<\/p>\n<p class=\"lead\">Auch die drei Weisen kamen nach Israel, und sie dachten, dass es am naheliegendsten w\u00e4re, im Haus des K\u00f6nigs Herodes nach einem K\u00f6nig zu suchen. Aber der b\u00f6se K\u00f6nig hatte nichts von einem K\u00f6nigssohn geh\u00f6rt, der geboren werden sollte. Und sowas h\u00f6rte er auch nicht so gerne, denn Herodes war ein K\u00f6nig, der alles tun w\u00fcrde, um seine Macht zu behalten. Er schmiedete einen b\u00f6sen Plan f\u00fcr den Fall, dass die Weisen Recht hatten und der Sohn eines K\u00f6nigs tats\u00e4chlich geboren wurde. Au\u00dferdem befiehlt er den Weisen, zu ihm zur\u00fcckzukommen und ihm zu berichten, was sie gefunden haben.<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-64705\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2022\/05\/film.png\" alt=\"\" width=\"40\" height=\"40\">&nbsp;Heute ist euch ein Retter geboren<\/h3>\n<p class=\"lead\"><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-84420 alignleft\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/11\/poster-VX-399990-10-07-24-02-711x400.jpg\" alt=\"\" width=\"500\" height=\"281\">In dieser Folge erfahren wir, wie es mit dem b\u00f6sen Herodes, den drei Weisen, Maria, Josef und dem Jesuskind weiterging. Wir treffen auch die Hirten auf dem Feld, die von Engeln besucht wurden, die ihnen die gro\u00dfe Freude verk\u00fcndeten, dass nun ein Erl\u00f6ser geboren wurde. Sie gingen sofort nach Bethlehem, um das kleine Kind zu sehen.<\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559740\":240}\">&nbsp;<\/span><\/p>\n<p class=\"lead\"><span data-contrast=\"auto\">Herodes erkennt, dass in Bethlehem etwas im Gange ist. Die Weisen kehren nicht mehr in sein Schloss zur\u00fcck, denn sie erkennen, dass der K\u00f6nig etwas B\u00f6ses im Schilde f\u00fchrt. Der K\u00f6nig beschlie\u00dft, seine Soldaten nach Bethlehem zu schicken. Aber nachts kommt ein Engel und warnt Josef und r\u00e4t ihm, nach \u00c4gypten zu fliehen. Er, Maria und das neugeborene Baby fliehen und tun, wie der Engel gesagt hat. So kommen sie nach \u00c4gypten, wo Jesus seine ersten Lebensjahre verbringt. Er wird unser Retter und der Erl\u00f6ser der Welt sein. Eine neue Hoffnung ist auf die Erde gekommen.<\/span><span data-ccp-props=\"{\"134233117\":false,\"134233118\":false,\"201341983\":0,\"335559740\":240}\">&nbsp;<\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1880489423\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1178579282\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1365091007\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_794199080 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(247, 247, 247);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<p>Was vor \u00fcber 2000 Jahren in der kleinen Stadt Bethlehem geschah, hat seit Generationen auf der ganzen Welt Hoffnung, Freude und Dankbarkeit ausgel\u00f6st. Die Weihnachtsgeschichte ist sowohl f\u00fcr Kinder als auch f\u00fcr Erwachsene ansprechend und spannend.<\/p>\n","protected":false},"author":9614,"featured_media":43762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"bcc_login_visibility":1,"bcc_groups":[],"bcc_groups_email":true,"bcc_visibility_groups":[],"bcc_visibility_groups_email":false,"sent_notifications":[],"footnotes":"","_links_to":"","_links_to_target":""},"categories":[164,128],"tags":[],"class_list":["post-84203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-6-11-jahre","category-themenseiten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Reise zum Anfang - eine Weihnachtsgeschichte - Bible Kids<\/title>\n<meta name=\"description\" content=\"Die Reise zum Anfang - eine Weihnachtsgeschichte zum Ereignis in der kleinen Stadt Bethlehem vor \u00fcber 2000 Jahren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Reise zum Anfang - eine Weihnachtsgeschichte - Bible Kids\" \/>\n<meta property=\"og:description\" content=\"Die Reise zum Anfang - eine Weihnachtsgeschichte zum Ereignis in der kleinen Stadt Bethlehem vor \u00fcber 2000 Jahren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/\" \/>\n<meta property=\"og:site_name\" content=\"Bible Kids\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-29T09:24:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-30T19:12:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/NATI_03.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2011\" \/>\n\t<meta property=\"og:image:height\" content=\"1472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"15974\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"15974\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/die-reise-zum-anfang-eine-weihnachtsgeschichte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/die-reise-zum-anfang-eine-weihnachtsgeschichte\\\/\"},\"author\":{\"name\":\"15974\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\"},\"headline\":\"Die Reise zum Anfang &#8211; eine Weihnachtsgeschichte\",\"datePublished\":\"2023-11-29T09:24:25+00:00\",\"dateModified\":\"2024-11-30T19:12:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/die-reise-zum-anfang-eine-weihnachtsgeschichte\\\/\"},\"wordCount\":761,\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/die-reise-zum-anfang-eine-weihnachtsgeschichte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/NATI_03.png\",\"articleSection\":[\"6-11 Jahre\",\"Themenseiten\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/die-reise-zum-anfang-eine-weihnachtsgeschichte\\\/\",\"url\":\"https:\\\/\\\/biblekids.io\\\/de\\\/die-reise-zum-anfang-eine-weihnachtsgeschichte\\\/\",\"name\":\"Die Reise zum Anfang - eine Weihnachtsgeschichte - Bible Kids\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/die-reise-zum-anfang-eine-weihnachtsgeschichte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/die-reise-zum-anfang-eine-weihnachtsgeschichte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/NATI_03.png\",\"datePublished\":\"2023-11-29T09:24:25+00:00\",\"dateModified\":\"2024-11-30T19:12:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\"},\"description\":\"Die Reise zum Anfang - eine Weihnachtsgeschichte zum Ereignis in der kleinen Stadt Bethlehem vor \u00fcber 2000 Jahren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/die-reise-zum-anfang-eine-weihnachtsgeschichte\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biblekids.io\\\/de\\\/die-reise-zum-anfang-eine-weihnachtsgeschichte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/die-reise-zum-anfang-eine-weihnachtsgeschichte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/NATI_03.png\",\"contentUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/NATI_03.png\",\"width\":2011,\"height\":1472,\"caption\":\"KIDS_E28_Kinderweihnachten \u2013 Als Jesus geboren wurde\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/de\\\/die-reise-zum-anfang-eine-weihnachtsgeschichte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/biblekids.io\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Reise zum Anfang &#8211; eine Weihnachtsgeschichte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\",\"url\":\"https:\\\/\\\/biblekids.io\\\/no\\\/\",\"name\":\"Bible Kids\",\"description\":\"Bibelgeschichten f\u00fcr Kinder\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biblekids.io\\\/no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\",\"name\":\"15974\",\"url\":\"https:\\\/\\\/biblekids.io\\\/de\\\/author\\\/15974\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Reise zum Anfang - eine Weihnachtsgeschichte - Bible Kids","description":"Die Reise zum Anfang - eine Weihnachtsgeschichte zum Ereignis in der kleinen Stadt Bethlehem vor \u00fcber 2000 Jahren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/","og_locale":"de_DE","og_type":"article","og_title":"Die Reise zum Anfang - eine Weihnachtsgeschichte - Bible Kids","og_description":"Die Reise zum Anfang - eine Weihnachtsgeschichte zum Ereignis in der kleinen Stadt Bethlehem vor \u00fcber 2000 Jahren.","og_url":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/","og_site_name":"Bible Kids","article_published_time":"2023-11-29T09:24:25+00:00","article_modified_time":"2024-11-30T19:12:40+00:00","og_image":[{"width":2011,"height":1472,"url":"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/NATI_03.png","type":"image\/png"}],"author":"15974","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"15974","Gesch\u00e4tzte Lesezeit":"6 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/#article","isPartOf":{"@id":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/"},"author":{"name":"15974","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22"},"headline":"Die Reise zum Anfang &#8211; eine Weihnachtsgeschichte","datePublished":"2023-11-29T09:24:25+00:00","dateModified":"2024-11-30T19:12:40+00:00","mainEntityOfPage":{"@id":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/"},"wordCount":761,"image":{"@id":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/NATI_03.png","articleSection":["6-11 Jahre","Themenseiten"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/","url":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/","name":"Die Reise zum Anfang - eine Weihnachtsgeschichte - Bible Kids","isPartOf":{"@id":"https:\/\/biblekids.io\/no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/#primaryimage"},"image":{"@id":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/NATI_03.png","datePublished":"2023-11-29T09:24:25+00:00","dateModified":"2024-11-30T19:12:40+00:00","author":{"@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22"},"description":"Die Reise zum Anfang - eine Weihnachtsgeschichte zum Ereignis in der kleinen Stadt Bethlehem vor \u00fcber 2000 Jahren.","breadcrumb":{"@id":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/#primaryimage","url":"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/NATI_03.png","contentUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/NATI_03.png","width":2011,"height":1472,"caption":"KIDS_E28_Kinderweihnachten \u2013 Als Jesus geboren wurde"},{"@type":"BreadcrumbList","@id":"https:\/\/biblekids.io\/de\/die-reise-zum-anfang-eine-weihnachtsgeschichte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/biblekids.io\/ru\/"},{"@type":"ListItem","position":2,"name":"Die Reise zum Anfang &#8211; eine Weihnachtsgeschichte"}]},{"@type":"WebSite","@id":"https:\/\/biblekids.io\/no\/#website","url":"https:\/\/biblekids.io\/no\/","name":"Bible Kids","description":"Bibelgeschichten f\u00fcr Kinder","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biblekids.io\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22","name":"15974","url":"https:\/\/biblekids.io\/de\/author\/15974\/"}]}},"_links":{"self":[{"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/posts\/84203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/users\/9614"}],"replies":[{"embeddable":true,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/comments?post=84203"}],"version-history":[{"count":8,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/posts\/84203\/revisions"}],"predecessor-version":[{"id":89738,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/posts\/84203\/revisions\/89738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/media\/43762"}],"wp:attachment":[{"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/media?parent=84203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/categories?post=84203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biblekids.io\/de\/wp-json\/wp\/v2\/tags?post=84203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}