{"id":45371,"date":"2021-02-02T11:10:53","date_gmt":"2021-02-02T10:10:53","guid":{"rendered":"https:\/\/biblekids.io\/?p=45371"},"modified":"2021-04-26T14:14:06","modified_gmt":"2021-04-26T12:14:06","slug":"ven-a-jesus-el-ayuda-parte-2","status":"publish","type":"post","link":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/","title":{"rendered":"Ven a Jes\u00fas, \u00c9l ayuda &#8211; Parte 2"},"content":{"rendered":"\n\t<section class=\"section\" id=\"section_533510928\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-506575962\">\n\n\t<div id=\"col-529974100\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>M\u00e1s sobre el tema<\/h2>\n<p class=\"lead\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-46597\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/03\/poster-VX-368640-00-05-24-12-711x400.jpg\" alt=\"\" width=\"500\" height=\"281\">Jes\u00fas amaba a las personas y quer\u00eda ense\u00f1arles a guardar la palabra de Dios. \u00c9l anuncio la palabra de Dios con poder, porque tambi\u00e9n \u00c9l vivi\u00f3 la Palabra. Pero a los fariseos que viv\u00edan en esos d\u00edas no les gust\u00f3.  <\/p>\n<p class=\"lead\">Los fariseos eran considerados hombres santos muy importantes que se aseguraban de que el pueblo de Israel guardara la ley de Dios. Los fariseos hab\u00edan le\u00eddo la mayor\u00eda de las escrituras y deb\u00edan saber todo acerca de Dios. Pero Jes\u00fas sab\u00eda que eran falsos. \u00abHip\u00f3critas, generaci\u00f3n de v\u00edboras\u00bb, asi los llam\u00f3. Jes\u00fas era el propio Hijo de Dios y conoc\u00eda a Dios. Por tanto, Jes\u00fas sab\u00eda que la forma en que los fariseos se comportaban y usaban la fuerza contra los jud\u00edos era todo lo contrario de lo que Dios quer\u00eda. No eran santos y puros. No hab\u00edan entendido nada de c\u00f3mo es Dios y c\u00f3mo quiere que seamos los humanos.       <\/p>\n<p class=\"lead\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-46571\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/03\/poster-VX-368640-00-02-19-22-711x400.jpg\" alt=\"\" width=\"500\" height=\"281\">A Jes\u00fas no le importaba que a los fariseos no les agradara, ni que ellos estuvieran planeando matarle. M\u00e1s bien, us\u00f3 el tiempo para hablar la palabra de Dios y ense\u00f1ar a las personas a ser verdaderas y genuinas. Jes\u00fas dijo: El que oye mi palabra y cree en el que me envi\u00f3, tiene vida eterna. Y de los fariseos dijo: \u00bfC\u00f3mo pod\u00e9is vosotros creer, pues recib\u00eds gloria los unos de los otros, y no busc\u00e1is la gloria que viene del Dios \u00fanico?   <\/p>\n<p class=\"lead\">Lo que podemos aprender de esta historia es que la hipocres\u00eda, fingir, ser\u00e1 muy perjudicial para nosotros. Dios quiere que seamos verdaderos y genuinos, y que no pretendamos ser nada m\u00e1s que mejores de lo que realmente somos. Dios mira al coraz\u00f3n y lo sabe todo. Ama a todos los que lo buscan con un coraz\u00f3n puro y bueno.   <\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_533510928 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(247, 247, 247);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row row-collapse row-full-width\"  id=\"row-738810204\">\n\n\t<div id=\"col-731213530\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1609684069\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"594\" height=\"607\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/03\/BIHE_INSTAGRAM_E05.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1609684069 {\n  padding-top: 640px;\n}\n#banner-1609684069 .overlay {\n  background-color: rgba(0,0,0,.5);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-643303135\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-551610863\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1583912666\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text \">\n              \n              <div class=\"text-inner text-left\">\n                  \n\t<div id=\"gap-193247974\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-193247974 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<h2><strong>M\u00e1s sobre la pel\u00edcula animada<\/strong><\/h2>\n<p class=\"lead\"><span style=\"font-size: 140%;\">La pel\u00edcula contin\u00faa la historia del hombre a quien Jes\u00fas hab\u00eda sanado junto al estanque de Betesda. Los fariseos vieron a este hombre caminar y cargar su lecho. Realmente no cre\u00edan que deb\u00eda hacer esto ,en el d\u00eda de reposo, un s\u00e1bado. Intentaron averiguar qui\u00e9n hab\u00eda obligado al hombre a hacer esto y pronto descubrieron que era Jes\u00fas quien lo hab\u00eda sanado. Esto enfureci\u00f3 mucho a los fariseos. Jes\u00fas no solo sano a las personas, sino que adem\u00e1s tambi\u00e9n les hizo creer en lo que les hablaba. . Los fariseos comenzaron a conspirar para matar a Jes\u00fas. Pero Jes\u00fas sab\u00eda que a\u00fan no hab\u00eda llegado el momento de capturarlo, as\u00ed que aprovech\u00f3 el tiempo para hablar la palabra de Dios a la gente y les dio esperanza.       <\/span><\/p>\n\t<div id=\"gap-1122679886\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1122679886 {\n  padding-top: 5px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1788182547\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1788182547 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1583912666 {\n  width: 78%;\n}\n#text-box-1583912666 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1583912666 {\n    width: 79%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-551610863 {\n  padding-top: 650px;\n  background-color: rgb(255, 255, 255);\n}\n@media (min-width:550px) {\n  #banner-551610863 {\n    padding-top: 640px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n\t<section class=\"section\" id=\"section_1165210765\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1374451983\">\n\n\t<div id=\"col-1975310709\" class=\"col medium-11 small-12 large-11\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p class=\"lead\"><strong>Consejos para la escuela dominical<\/strong><\/p>\n<p class=\"lead\">Recomendamos utilizar el dise\u00f1o presentado en la Parte 1 de este tema. Es bueno poder tener algo permanente que los ni\u00f1os conozcan, y es m\u00e1s f\u00e1cil dirigir una escuela dominical cuando tienes algunas pautas fijas <strong> <\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"389\">\n<p class=\"lead\">1. Bienvenida \u2013 introducci\u00f3n del tema<\/p>\n<\/td>\n<td width=\"144\">\n<p class=\"lead\">3 minutos<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"389\">\n<p class=\"lead\">2. Canci\u00f3n corta \u2013 una que puedan<\/p>\n<\/td>\n<td width=\"144\">\n<p class=\"lead\">2 minutos<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"389\">\n<p class=\"lead\">3. Video<\/p>\n<\/td>\n<td width=\"144\">\n<p class=\"lead\">5 minutos aprox.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"389\">\n<p class=\"lead\">4. Conversaci\u00f3n, donde los ni\u00f1os pueden preguntar y participar.<\/p>\n<\/td>\n<td width=\"144\">\n<p class=\"lead\">10 minutos m\u00e1ximo<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"389\">\n<p class=\"lead\">5. Canci\u00f3n relacionada con el tema<\/p>\n<\/td>\n<td width=\"144\">\n<p class=\"lead\">2-3 minutos<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"389\">\n<p class=\"lead\">6. Una actividad o concurso de preguntas.<\/p>\n<\/td>\n<td width=\"144\">\n<p class=\"lead\">La duraci\u00f3n depende del tipo de actividad, pero tambi\u00e9n del tiempo.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"389\">\n<p class=\"lead\">7. Gracias por hoy<\/p>\n<\/td>\n<td width=\"144\">\n<p class=\"lead\">1 minuto<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"389\">\n<p class=\"lead\">Duraci\u00f3n total de la actividad <\/p>\n<\/td>\n<td width=\"144\">\n<p class=\"lead\">25 minutos m\u00e1ximo<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"row\"  id=\"row-835493616\">\n\n\t<div id=\"col-579179007\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"col-2054887327\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<h3><strong>Preguntas para conversar<\/strong><\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-small\"  id=\"row-535401499\">\n\n\t<div id=\"col-221580719\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-742896044\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                    <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1287256018\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p class=\"lead\" style=\"text-align: center;\"><strong>1. \u00bfPor qu\u00e9 a los fariseos no les gust\u00f3 que Jes\u00fas sanara a un hombre un s\u00e1bado?<\/strong><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1287256018 {\n  width: 79%;\n}\n#text-box-1287256018 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-742896044 {\n  padding-top: 180px;\n  background-color: rgb(138, 66, 131);\n}\n#banner-742896044 .overlay {\n  background-color: rgba(0, 0, 0, 0.5);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-184146776\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1766521767\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                    <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-2132031819\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p class=\"lead\"><strong>2. \u00bfPor qu\u00e9 Jes\u00fas llam\u00f3 hip\u00f3critas a los fariseos? \u00bfY qu\u00e9 significa hipocres\u00eda?<\/strong><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-2132031819 {\n  width: 79%;\n}\n#text-box-2132031819 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1766521767 {\n  padding-top: 180px;\n}\n#banner-1766521767 .overlay {\n  background-color: rgba(0,0,0,.5);\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"is-divider divider clearfix\" style=\"height:53px;background-color:rgba(250, 245, 245, 0.56);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1413032774\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-39855697\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                    <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1313238442\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p class=\"lead\"><strong>3. \u00bfPor qu\u00e9 es tan importante ser sincero y genuino?<\/strong><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1313238442 {\n  width: 79%;\n}\n#text-box-1313238442 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-39855697 {\n  padding-top: 180px;\n}\n#banner-39855697 .overlay {\n  background-color: rgba(0,0,0,.5);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1684679999\">\n\n\t<div id=\"col-846065019\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2><span style=\"font-size: 75%;\"><strong>Vers\u00edculos de la Biblia que combinan con el tema:<\/strong><\/span><\/h2>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1406838294\">\n\n\t<div id=\"col-117643490\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<blockquote>\n<p>Juan 5, 44: \u00bfC\u00f3mo pod\u00e9is vosotros creer, pues recib\u00eds gloria los unos de los otros, y no busc\u00e1is la gloria que viene del Dios \u00fanico? <\/p>\n<\/blockquote>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1502336387\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<blockquote>\n<p>Hebreos 10: 22: acerqu\u00e9monos con coraz\u00f3n sincero, en plena certidumbre de fe, purificados los corazones de mala conciencia, y lavados los cuerpos con agua pura. <\/p>\n<\/blockquote>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1179351795\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<blockquote>\n<p>Santiago 4: 8: Acercaos a Dios, y \u00e9l se acercar\u00e1 a vosotros. Pecadores, limpiad las manos; y vosotros los de doble \u00e1nimo, purificad vuestros corazones.   <\/p>\n<\/blockquote>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1165210765 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(247, 247, 247);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<p>En este tema escucharemos la historia sobre Jes\u00fas y los fariseos. Los fariseos quer\u00edan aparentar ser muy buenos, pero Jes\u00fas quiere que seamos verdaderos y genuinos. <\/p>\n","protected":false},"author":9614,"featured_media":46488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"bcc_login_visibility":1,"bcc_groups":[],"bcc_groups_email":true,"bcc_visibility_groups":[],"bcc_visibility_groups_email":false,"sent_notifications":[],"footnotes":"","_links_to":"","_links_to_target":""},"categories":[166,137],"tags":[],"class_list":["post-45371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-6-11-anos","category-temas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ven a Jes\u00fas, \u00c9l ayuda - Parte 2 - Bible Kids<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ven a Jes\u00fas, \u00c9l ayuda - Parte 2 - Bible Kids\" \/>\n<meta property=\"og:description\" content=\"En este tema escucharemos la historia sobre Jes\u00fas y los fariseos. Los fariseos quer\u00edan aparentar ser muy buenos, pero Jes\u00fas quiere que seamos verdaderos y genuinos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Bible Kids\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-02T10:10:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-26T12:14:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/02\/ikon_BIHE_E05.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1924\" \/>\n\t<meta property=\"og:image:height\" content=\"935\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"15974\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"15974\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/ven-a-jesus-el-ayuda-parte-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/ven-a-jesus-el-ayuda-parte-2\\\/\"},\"author\":{\"name\":\"15974\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\"},\"headline\":\"Ven a Jes\u00fas, \u00c9l ayuda &#8211; Parte 2\",\"datePublished\":\"2021-02-02T10:10:53+00:00\",\"dateModified\":\"2021-04-26T12:14:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/ven-a-jesus-el-ayuda-parte-2\\\/\"},\"wordCount\":962,\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/ven-a-jesus-el-ayuda-parte-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/ikon_BIHE_E05.png\",\"articleSection\":[\"6-11 a\u00f1os\",\"Temas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/ven-a-jesus-el-ayuda-parte-2\\\/\",\"url\":\"https:\\\/\\\/biblekids.io\\\/es\\\/ven-a-jesus-el-ayuda-parte-2\\\/\",\"name\":\"Ven a Jes\u00fas, \u00c9l ayuda - Parte 2 - Bible Kids\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/ven-a-jesus-el-ayuda-parte-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/ven-a-jesus-el-ayuda-parte-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/ikon_BIHE_E05.png\",\"datePublished\":\"2021-02-02T10:10:53+00:00\",\"dateModified\":\"2021-04-26T12:14:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/ven-a-jesus-el-ayuda-parte-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biblekids.io\\\/es\\\/ven-a-jesus-el-ayuda-parte-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/ven-a-jesus-el-ayuda-parte-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/ikon_BIHE_E05.png\",\"contentUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/ikon_BIHE_E05.png\",\"width\":1924,\"height\":935,\"caption\":\"Come to Jesus - He will help you\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/ven-a-jesus-el-ayuda-parte-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/biblekids.io\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ven a Jes\u00fas, \u00c9l ayuda &#8211; Parte 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\",\"url\":\"https:\\\/\\\/biblekids.io\\\/no\\\/\",\"name\":\"Bible Kids\",\"description\":\"Historias b\u00edblicas para ni\u00f1os\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biblekids.io\\\/no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\",\"name\":\"15974\",\"url\":\"https:\\\/\\\/biblekids.io\\\/es\\\/author\\\/15974\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ven a Jes\u00fas, \u00c9l ayuda - Parte 2 - Bible Kids","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/","og_locale":"es_ES","og_type":"article","og_title":"Ven a Jes\u00fas, \u00c9l ayuda - Parte 2 - Bible Kids","og_description":"En este tema escucharemos la historia sobre Jes\u00fas y los fariseos. Los fariseos quer\u00edan aparentar ser muy buenos, pero Jes\u00fas quiere que seamos verdaderos y genuinos.","og_url":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/","og_site_name":"Bible Kids","article_published_time":"2021-02-02T10:10:53+00:00","article_modified_time":"2021-04-26T12:14:06+00:00","og_image":[{"width":1924,"height":935,"url":"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/02\/ikon_BIHE_E05.png","type":"image\/png"}],"author":"15974","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"15974","Tiempo de lectura":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/#article","isPartOf":{"@id":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/"},"author":{"name":"15974","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22"},"headline":"Ven a Jes\u00fas, \u00c9l ayuda &#8211; Parte 2","datePublished":"2021-02-02T10:10:53+00:00","dateModified":"2021-04-26T12:14:06+00:00","mainEntityOfPage":{"@id":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/"},"wordCount":962,"image":{"@id":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/02\/ikon_BIHE_E05.png","articleSection":["6-11 a\u00f1os","Temas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/","url":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/","name":"Ven a Jes\u00fas, \u00c9l ayuda - Parte 2 - Bible Kids","isPartOf":{"@id":"https:\/\/biblekids.io\/no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/#primaryimage"},"image":{"@id":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/02\/ikon_BIHE_E05.png","datePublished":"2021-02-02T10:10:53+00:00","dateModified":"2021-04-26T12:14:06+00:00","author":{"@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22"},"breadcrumb":{"@id":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/#primaryimage","url":"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/02\/ikon_BIHE_E05.png","contentUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/02\/ikon_BIHE_E05.png","width":1924,"height":935,"caption":"Come to Jesus - He will help you"},{"@type":"BreadcrumbList","@id":"https:\/\/biblekids.io\/es\/ven-a-jesus-el-ayuda-parte-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/biblekids.io\/es\/"},{"@type":"ListItem","position":2,"name":"Ven a Jes\u00fas, \u00c9l ayuda &#8211; Parte 2"}]},{"@type":"WebSite","@id":"https:\/\/biblekids.io\/no\/#website","url":"https:\/\/biblekids.io\/no\/","name":"Bible Kids","description":"Historias b\u00edblicas para ni\u00f1os","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biblekids.io\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22","name":"15974","url":"https:\/\/biblekids.io\/es\/author\/15974\/"}]}},"_links":{"self":[{"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/posts\/45371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/users\/9614"}],"replies":[{"embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/comments?post=45371"}],"version-history":[{"count":0,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/posts\/45371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/media\/46488"}],"wp:attachment":[{"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/media?parent=45371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/categories?post=45371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/tags?post=45371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}