{"id":45638,"date":"2020-10-12T14:19:50","date_gmt":"2020-10-12T12:19:50","guid":{"rendered":"https:\/\/biblekids.io\/jesus-esta-sempre-conosco\/"},"modified":"2023-01-17T09:20:06","modified_gmt":"2023-01-17T08:20:06","slug":"jesus-esta-sempre-conosco","status":"publish","type":"post","link":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/","title":{"rendered":"Jesus est\u00e1 sempre conosco"},"content":{"rendered":"\n\t<section class=\"section\" id=\"section_331732193\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1652882731\">\n\n\t<div id=\"col-687901856\" class=\"col large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>M\u00e1s sobre el tema<\/h2>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1582498558\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_782774157\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/10\/poster-VX-356291-00-02-10-00-1400x788.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_782774157 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-951935840\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p class=\"lead\">Este episodio de la Escuela Dominical en L\u00ednea es una producci\u00f3n con contribuciones de diferentes pa\u00edses de \u00c1frica. El programa est\u00e1 dirigido por dos presentadores de Sud\u00e1frica y la transmisi\u00f3n ofrece buena m\u00fasica, palabras alentadoras y un nuevo episodio de la serie \u201cHijos de Dios\u201d.  M\u00e1s adelante en la transmisi\u00f3n de la reuni\u00f3n veremos a unos ni\u00f1os de Camer\u00fan que tambi\u00e9n ir\u00e1n de paseo en barco, \u00bfestar\u00e1n preparados para vencer sus miedos?<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-69742395\" class=\"col no-bottom-padding small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3>Jesus acalma a tempestade<\/h3>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-69742395 > .col-inner {\n  margin: 30px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1486699980\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p class=\"lead\">En el episodio de \u201cHijos de Dios\u201d veremos el d\u00eda en que Jes\u00fas quer\u00eda que sus disc\u00edpulos fueran con la barca al otro lado del mar. \u00c9l estaba cansado despu\u00e9s de un largo d\u00eda y se fue a descansar en la barca. Pero de repente vino una tormenta muy fuerte. Los disc\u00edpulos ten\u00edan miedo y despertaron a Jes\u00fas. Ah\u00ed el hizo algo inesperado. Jes\u00fas se levant\u00f3, amenaz\u00f3 al viento y le dijo al mar: \u201c\u00a1Tranquilo! \u00a1Qu\u00e9date quieto!\u201d De repente el viento y el agua se tranquilizaron. Entonces Jes\u00fas les dijo a sus disc\u00edpulos: \u201c\u00bfPor qu\u00e9 ten\u00edan miedo? \u00bfno tienen fe?\u201d Esto fue algo que los disc\u00edpulos jam\u00e1s olvidaron, y es algo que tambi\u00e9n puede darnos seguridad hoy en d\u00eda. Jes\u00fas est\u00e1 siempre con nosotros, no debemos temer a nada.       <\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2074583949\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2114764807\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/10\/GUBA_S01_E05_STILL1-1400x788.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2114764807 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_331732193 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(247, 247, 247);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<p>\u00abTodo el poder me es dado en el cielo y en la tierra.\u00bb, les dijo Jes\u00fas a sus disc\u00edpulos. Por lo que no necesitaban tener miedo, como esa vez cuando estaban navegando en su barca y se encontraron en el medio de la tormenta. Sobre esto escucharemos m\u00e1s en este tema. Un poco antes de que \u00e9l ascendiera al cielo, a Dios, Jes\u00fas nos dio una promesa; \u201dYo estar\u00e9 con ustedes todos los d\u00edas hasta el fin del mundo\u201d.   <\/p>\n","protected":false},"author":5,"featured_media":42192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"bcc_login_visibility":1,"bcc_groups":[],"bcc_groups_email":true,"bcc_visibility_groups":[],"bcc_visibility_groups_email":false,"sent_notifications":[],"footnotes":"","_links_to":"","_links_to_target":""},"categories":[166,137],"tags":[],"class_list":["post-45638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-6-11-anos","category-temas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jesus est\u00e1 sempre conosco - Bible Kids<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jesus est\u00e1 sempre conosco - Bible Kids\" \/>\n<meta property=\"og:description\" content=\"\u00abTodo el poder me es dado en el cielo y en la tierra.\u00bb, les dijo Jes\u00fas a sus disc\u00edpulos. Por lo que no necesitaban tener miedo, como esa vez cuando estaban navegando en su barca y se encontraron en el medio de la tormenta. Sobre esto escucharemos m\u00e1s en este tema. Un poco antes de que \u00e9l ascendiera al cielo, a Dios, Jes\u00fas nos dio una promesa; \u201dYo estar\u00e9 con ustedes todos los d\u00edas hasta el fin del mundo\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/\" \/>\n<meta property=\"og:site_name\" content=\"Bible Kids\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-12T12:19:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-17T08:20:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/Ikon_GUBA_jesus.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"1895\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"biblekids.io\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"biblekids.io\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/jesus-esta-sempre-conosco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/jesus-esta-sempre-conosco\\\/\"},\"author\":{\"name\":\"biblekids.io\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/98e151315777c437cac5d2a30edc5143\"},\"headline\":\"Jesus est\u00e1 sempre conosco\",\"datePublished\":\"2020-10-12T12:19:50+00:00\",\"dateModified\":\"2023-01-17T08:20:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/jesus-esta-sempre-conosco\\\/\"},\"wordCount\":293,\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/jesus-esta-sempre-conosco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Ikon_GUBA_jesus.png\",\"articleSection\":[\"6-11 a\u00f1os\",\"Temas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/jesus-esta-sempre-conosco\\\/\",\"url\":\"https:\\\/\\\/biblekids.io\\\/es\\\/jesus-esta-sempre-conosco\\\/\",\"name\":\"Jesus est\u00e1 sempre conosco - Bible Kids\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/jesus-esta-sempre-conosco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/jesus-esta-sempre-conosco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Ikon_GUBA_jesus.png\",\"datePublished\":\"2020-10-12T12:19:50+00:00\",\"dateModified\":\"2023-01-17T08:20:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/98e151315777c437cac5d2a30edc5143\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/jesus-esta-sempre-conosco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biblekids.io\\\/es\\\/jesus-esta-sempre-conosco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/jesus-esta-sempre-conosco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Ikon_GUBA_jesus.png\",\"contentUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Ikon_GUBA_jesus.png\",\"width\":2480,\"height\":1895,\"caption\":\"Jesus is always with us - Jesus calms the storm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/jesus-esta-sempre-conosco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/biblekids.io\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jesus est\u00e1 sempre conosco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\",\"url\":\"https:\\\/\\\/biblekids.io\\\/no\\\/\",\"name\":\"Bible Kids\",\"description\":\"Historias b\u00edblicas para ni\u00f1os\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biblekids.io\\\/no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/98e151315777c437cac5d2a30edc5143\",\"name\":\"biblekids.io\",\"url\":\"https:\\\/\\\/biblekids.io\\\/es\\\/author\\\/42677\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jesus est\u00e1 sempre conosco - Bible Kids","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/","og_locale":"es_ES","og_type":"article","og_title":"Jesus est\u00e1 sempre conosco - Bible Kids","og_description":"\u00abTodo el poder me es dado en el cielo y en la tierra.\u00bb, les dijo Jes\u00fas a sus disc\u00edpulos. Por lo que no necesitaban tener miedo, como esa vez cuando estaban navegando en su barca y se encontraron en el medio de la tormenta. Sobre esto escucharemos m\u00e1s en este tema. Un poco antes de que \u00e9l ascendiera al cielo, a Dios, Jes\u00fas nos dio una promesa; \u201dYo estar\u00e9 con ustedes todos los d\u00edas hasta el fin del mundo\u201d.","og_url":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/","og_site_name":"Bible Kids","article_published_time":"2020-10-12T12:19:50+00:00","article_modified_time":"2023-01-17T08:20:06+00:00","og_image":[{"width":2480,"height":1895,"url":"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/Ikon_GUBA_jesus.png","type":"image\/png"}],"author":"biblekids.io","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"biblekids.io","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/#article","isPartOf":{"@id":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/"},"author":{"name":"biblekids.io","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/98e151315777c437cac5d2a30edc5143"},"headline":"Jesus est\u00e1 sempre conosco","datePublished":"2020-10-12T12:19:50+00:00","dateModified":"2023-01-17T08:20:06+00:00","mainEntityOfPage":{"@id":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/"},"wordCount":293,"image":{"@id":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/Ikon_GUBA_jesus.png","articleSection":["6-11 a\u00f1os","Temas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/","url":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/","name":"Jesus est\u00e1 sempre conosco - Bible Kids","isPartOf":{"@id":"https:\/\/biblekids.io\/no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/#primaryimage"},"image":{"@id":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/Ikon_GUBA_jesus.png","datePublished":"2020-10-12T12:19:50+00:00","dateModified":"2023-01-17T08:20:06+00:00","author":{"@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/98e151315777c437cac5d2a30edc5143"},"breadcrumb":{"@id":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/#primaryimage","url":"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/Ikon_GUBA_jesus.png","contentUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2020\/11\/Ikon_GUBA_jesus.png","width":2480,"height":1895,"caption":"Jesus is always with us - Jesus calms the storm"},{"@type":"BreadcrumbList","@id":"https:\/\/biblekids.io\/es\/jesus-esta-sempre-conosco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/biblekids.io\/es\/"},{"@type":"ListItem","position":2,"name":"Jesus est\u00e1 sempre conosco"}]},{"@type":"WebSite","@id":"https:\/\/biblekids.io\/no\/#website","url":"https:\/\/biblekids.io\/no\/","name":"Bible Kids","description":"Historias b\u00edblicas para ni\u00f1os","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biblekids.io\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/98e151315777c437cac5d2a30edc5143","name":"biblekids.io","url":"https:\/\/biblekids.io\/es\/author\/42677\/"}]}},"_links":{"self":[{"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/posts\/45638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/comments?post=45638"}],"version-history":[{"count":4,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/posts\/45638\/revisions"}],"predecessor-version":[{"id":57925,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/posts\/45638\/revisions\/57925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/media\/42192"}],"wp:attachment":[{"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/media?parent=45638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/categories?post=45638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/tags?post=45638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}