{"id":47432,"date":"2021-04-08T10:08:20","date_gmt":"2021-04-08T08:08:20","guid":{"rendered":"https:\/\/biblekids.io\/?p=47432"},"modified":"2021-05-31T12:11:25","modified_gmt":"2021-05-31T10:11:25","slug":"pablo-parte-1","status":"publish","type":"post","link":"https:\/\/biblekids.io\/es\/pablo-parte-1\/","title":{"rendered":"Pablo &#8211; Una vida completamente nueva"},"content":{"rendered":"<div class=\"row\"  id=\"row-1548699133\">\n\n\t<div id=\"col-37670334\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<section class=\"section\" id=\"section_1552587566\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<h3><strong>M\u00e1s sobre el tema<\/strong><\/h3>\n<p class=\"lead\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48750 alignright\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/05\/Skjermbilde-2021-05-26-kl.-12.09.44-681x400.png\" alt=\"\" width=\"500\" height=\"294\">Pablo naci\u00f3 en una familia jud\u00eda acomodada. \u00c9l ten\u00eda un futuro brillante por delante. Cuando ten\u00eda 14 a\u00f1os fue enviado a la mejor escuela en Jerusal\u00e9n para convertirse en un jud\u00edo fariseo. Un fariseo es una persona que sab\u00eda mucho acerca de la doctrina y las leyes jud\u00edas. Muchos de ellos eran poderosos, y a menudo usaban sus conocimientos para asegurarse de que los dem\u00e1s jud\u00edos siguieran las reglas que pensaban que eran correctas.    <\/p>\n<p class=\"lead\">Una cosa que Pablo y los otros fariseos no cre\u00edan que era correcta, era creer que Jes\u00fas era el Hijo de Dios y nuestro salvador. En aquel tiempo los que cre\u00edan en Jes\u00fas y se hac\u00edan llamar cristianos eran perseguidos, encarcelados e incluso apedreados. <\/p>\n<p class=\"lead\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48763 alignleft\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/05\/Skjermbilde-2021-05-26-kl.-12.11.47-698x400.png\" alt=\"\" width=\"500\" height=\"287\">Pablo era uno de los m\u00e1s celosos en perseguir a los cristianos. Puso todos sus esfuerzos en erradicar la fe en Jes\u00fas y estaba dispuesto a llegar m\u00e1s lejos que la mayor\u00eda. Incluso quer\u00eda seguir a los cristianos que hab\u00edan huido a Damasco para arrestarlos. Pero en el camino a Damasco sucedi\u00f3 algo curioso. Pablo experiment\u00f3 una luz resplandeciente del cielo y una voz le dijo: \u201c\u00bfPor qu\u00e9 me persigues?\u201d    <\/p>\n<p class=\"lead\">Era Jes\u00fas mismo quien habl\u00f3 a Pablo en ese momento. Ten\u00eda una tarea especial para Pablo, la cual, era anunciar el evangelio a todos los hombres. <\/p>\n<p class=\"lead\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48776 alignright\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/05\/Skjermbilde-2021-05-26-kl.-12.13.22-655x400.png\" alt=\"\" width=\"500\" height=\"305\">Pablo supo que Jes\u00fas le amaba, por eso no dudo ni un segundo. As\u00ed que Pablo ya estaba seguro de que Jes\u00fas era el verdadero Hijo de Dios. \u00a1Debido a este encuentro, Pablo cambi\u00f3 por completo! Aquel que antes estaba orgulloso de todo su poder y luch\u00f3 en contra de los cristianos, ten\u00eda una nueva meta en la vida.   <\/p>\n<p class=\"lead\">De ser un fariseo con poder y riquezas, Pablo pas\u00f3 a ser perseguido como cristiano. Hizo esto porque amaba a Jes\u00fas y porque se hab\u00eda dado cuenta de que nada ten\u00eda m\u00e1s valor que eso. Lo mismo ocurre con nosotros: tambi\u00e9n podemos tener a Jes\u00fas como Se\u00f1or y Maestro. Nada en este mundo es m\u00e1s valioso que eso.   <\/p>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1552587566 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(247, 247, 247);\n}\n<\/style>\n\t<\/section>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse row-full-width\"  id=\"row-1865574883\">\n\n\t<div id=\"col-1728198005\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1742573036\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/05\/BIHE_INSTAGRAM_E09.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n        <\/div>\n      <\/div>\n\n              <div class=\"height-fix is-invisible\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/05\/BIHE_INSTAGRAM_E09.jpg\" class=\"attachment-original size-original\" alt=\"\" \/><\/div>\n            \n<style>\n#banner-1742573036 .overlay {\n  background-color: rgba(0,0,0,.5);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2027076338\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-198345473\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1376175002\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text \">\n              \n              <div class=\"text-inner text-left\">\n                  \n\t<div id=\"gap-1893103550\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1893103550 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<h3><strong>M\u00e1s sobre la serie animada<\/strong><\/h3>\n<p class=\"lead\"><span style=\"font-size: 140%;\">En la pel\u00edcula conoceremos a Pablo como jud\u00edo acomodado que se convirti\u00f3 en fariseo y con la misi\u00f3n de perseguir a los cristianos y erradicar la fe en Jes\u00fas. Pero cuando se encontr\u00f3 con Jes\u00fas en el camino a Damasco, todo cambio. Pablo recibi\u00f3 un nuevo sentir y su vida tom\u00f3 una direcci\u00f3n completamente diferente. M\u00e1s tarde vino Ananias y or\u00f3 por \u00e9l para que recibiera de nuevo la vista y fuera llenado del Esp\u00edritu Santo. Pablo no s\u00f3lo recuper\u00f3 la vista, sino que adquiri\u00f3 una nueva visi\u00f3n de lo que realmente era importante en la vida. Cre\u00eda que lo ten\u00eda todo; conocimiento, dinero y poder. Pero se dio cuenta de que todo eso no val\u00eda nada. \u00a1Lo que Jes\u00fas pod\u00eda dar val\u00eda mucho m\u00e1s, much\u00edsimo m\u00e1s!       <\/span><\/p>\n\t<div id=\"gap-1755387588\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1755387588 {\n  padding-top: 5px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-829604349\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-829604349 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1376175002 {\n  width: 78%;\n}\n#text-box-1376175002 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1376175002 {\n    width: 78%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-198345473 {\n  padding-top: 650px;\n  background-color: rgb(255, 255, 255);\n}\n@media (min-width:550px) {\n  #banner-198345473 {\n    padding-top: 640px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n\t<section class=\"section\" id=\"section_145775068\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-591958161\">\n\n\t<div id=\"col-1578816800\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3>Preguntas sobre el tema<\/h3>\n<div class=\"row\"  id=\"row-1763331895\">\n\n\t<div id=\"col-1919292383\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1889317969\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-329128831\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p class=\"lead\"><span style=\"font-size: 180%;\">1. \u00bfQu\u00e9 estudi\u00f3 Pablo en Jer\u00fasalen?<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-329128831 {\n  width: 60%;\n}\n#text-box-329128831 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1889317969 {\n  padding-top: 120px;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1762977534\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-899026588\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-410637420\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p class=\"lead\"><span style=\"font-size: 180%;\">2. \u00bfQu\u00e9 le paso a pablo en el camino a Damasco?<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-410637420 {\n  width: 60%;\n}\n#text-box-410637420 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-899026588 {\n  padding-top: 120px;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-564552522\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1715511426\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-909925898\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p class=\"lead\"><span style=\"font-size: 180%;\">3. \u00bfQu\u00e9 sucedi\u00f3 despu\u00e9s de que Pablo se encontr\u00f3 con Jes\u00fas?<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-909925898 {\n  width: 60%;\n}\n#text-box-909925898 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1715511426 {\n  padding-top: 120px;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1351343707\">\n\n\t<div id=\"col-516955568\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3>Vers\u00edculos que se relacionan con el tema:<\/h3>\n<div class=\"row\"  id=\"row-2021615294\">\n\n\t<div id=\"col-522031773\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<blockquote>\n<p>Fil. 3.7 Pero cuantas cosas eran para m\u00ed ganancia, las he estimado como p\u00e9rdida por amor de Cristo. <\/p>\n<\/blockquote>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-355616689\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<blockquote>\n<p>Fil. 3. 13 &#8230;pero una cosa hago\u00d1 olvidando ciertamente lo que queda atr\u00e1s, y extendi\u00e9ndome a lo que est\u00e1 delante.<\/p>\n<\/blockquote>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-34860780\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_145775068 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(247, 247, 247);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<p>Pablo fue un temido perseguidor de cristianos. Pero un d\u00eda Jes\u00fas se le revel\u00f3, y entonces todo dio un giro en la vida de Pablo.   <\/p>\n","protected":false},"author":9614,"featured_media":48737,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"bcc_login_visibility":1,"bcc_groups":[],"bcc_groups_email":true,"bcc_visibility_groups":[],"bcc_visibility_groups_email":false,"sent_notifications":[],"footnotes":"","_links_to":"","_links_to_target":""},"categories":[166,137],"tags":[],"class_list":["post-47432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-6-11-anos","category-temas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pablo - Una vida completamente nueva - Bible Kids<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biblekids.io\/es\/pablo-parte-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pablo - Una vida completamente nueva - Bible Kids\" \/>\n<meta property=\"og:description\" content=\"Pablo fue un temido perseguidor de cristianos. Pero un d\u00eda Jes\u00fas se le revel\u00f3, y entonces todo dio un giro en la vida de Pablo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biblekids.io\/es\/pablo-parte-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Bible Kids\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-08T08:08:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-31T10:11:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/04\/MicrosoftTeams-image-19-1187x800.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1187\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"15974\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"15974\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/pablo-parte-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/pablo-parte-1\\\/\"},\"author\":{\"name\":\"15974\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\"},\"headline\":\"Pablo &#8211; Una vida completamente nueva\",\"datePublished\":\"2021-04-08T08:08:20+00:00\",\"dateModified\":\"2021-05-31T10:11:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/pablo-parte-1\\\/\"},\"wordCount\":788,\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/pablo-parte-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/MicrosoftTeams-image-19.png\",\"articleSection\":[\"6-11 a\u00f1os\",\"Temas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/pablo-parte-1\\\/\",\"url\":\"https:\\\/\\\/biblekids.io\\\/es\\\/pablo-parte-1\\\/\",\"name\":\"Pablo - Una vida completamente nueva - Bible Kids\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/pablo-parte-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/pablo-parte-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/MicrosoftTeams-image-19.png\",\"datePublished\":\"2021-04-08T08:08:20+00:00\",\"dateModified\":\"2021-05-31T10:11:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/pablo-parte-1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biblekids.io\\\/es\\\/pablo-parte-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/pablo-parte-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/MicrosoftTeams-image-19.png\",\"contentUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/MicrosoftTeams-image-19.png\",\"width\":2413,\"height\":1626},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/es\\\/pablo-parte-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/biblekids.io\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pablo &#8211; Una vida completamente nueva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\",\"url\":\"https:\\\/\\\/biblekids.io\\\/no\\\/\",\"name\":\"Bible Kids\",\"description\":\"Historias b\u00edblicas para ni\u00f1os\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biblekids.io\\\/no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\",\"name\":\"15974\",\"url\":\"https:\\\/\\\/biblekids.io\\\/es\\\/author\\\/15974\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pablo - Una vida completamente nueva - Bible Kids","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biblekids.io\/es\/pablo-parte-1\/","og_locale":"es_ES","og_type":"article","og_title":"Pablo - Una vida completamente nueva - Bible Kids","og_description":"Pablo fue un temido perseguidor de cristianos. Pero un d\u00eda Jes\u00fas se le revel\u00f3, y entonces todo dio un giro en la vida de Pablo.","og_url":"https:\/\/biblekids.io\/es\/pablo-parte-1\/","og_site_name":"Bible Kids","article_published_time":"2021-04-08T08:08:20+00:00","article_modified_time":"2021-05-31T10:11:25+00:00","og_image":[{"width":1187,"height":800,"url":"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/04\/MicrosoftTeams-image-19-1187x800.png","type":"image\/png"}],"author":"15974","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"15974","Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biblekids.io\/es\/pablo-parte-1\/#article","isPartOf":{"@id":"https:\/\/biblekids.io\/es\/pablo-parte-1\/"},"author":{"name":"15974","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22"},"headline":"Pablo &#8211; Una vida completamente nueva","datePublished":"2021-04-08T08:08:20+00:00","dateModified":"2021-05-31T10:11:25+00:00","mainEntityOfPage":{"@id":"https:\/\/biblekids.io\/es\/pablo-parte-1\/"},"wordCount":788,"image":{"@id":"https:\/\/biblekids.io\/es\/pablo-parte-1\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/04\/MicrosoftTeams-image-19.png","articleSection":["6-11 a\u00f1os","Temas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/biblekids.io\/es\/pablo-parte-1\/","url":"https:\/\/biblekids.io\/es\/pablo-parte-1\/","name":"Pablo - Una vida completamente nueva - Bible Kids","isPartOf":{"@id":"https:\/\/biblekids.io\/no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biblekids.io\/es\/pablo-parte-1\/#primaryimage"},"image":{"@id":"https:\/\/biblekids.io\/es\/pablo-parte-1\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/04\/MicrosoftTeams-image-19.png","datePublished":"2021-04-08T08:08:20+00:00","dateModified":"2021-05-31T10:11:25+00:00","author":{"@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22"},"breadcrumb":{"@id":"https:\/\/biblekids.io\/es\/pablo-parte-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biblekids.io\/es\/pablo-parte-1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/biblekids.io\/es\/pablo-parte-1\/#primaryimage","url":"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/04\/MicrosoftTeams-image-19.png","contentUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2021\/04\/MicrosoftTeams-image-19.png","width":2413,"height":1626},{"@type":"BreadcrumbList","@id":"https:\/\/biblekids.io\/es\/pablo-parte-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/biblekids.io\/es\/"},{"@type":"ListItem","position":2,"name":"Pablo &#8211; Una vida completamente nueva"}]},{"@type":"WebSite","@id":"https:\/\/biblekids.io\/no\/#website","url":"https:\/\/biblekids.io\/no\/","name":"Bible Kids","description":"Historias b\u00edblicas para ni\u00f1os","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biblekids.io\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22","name":"15974","url":"https:\/\/biblekids.io\/es\/author\/15974\/"}]}},"_links":{"self":[{"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/posts\/47432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/users\/9614"}],"replies":[{"embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/comments?post=47432"}],"version-history":[{"count":0,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/posts\/47432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/media\/48737"}],"wp:attachment":[{"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/media?parent=47432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/categories?post=47432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biblekids.io\/es\/wp-json\/wp\/v2\/tags?post=47432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}