{"id":71495,"date":"2023-05-15T14:26:54","date_gmt":"2023-05-15T12:26:54","guid":{"rendered":"https:\/\/biblekids.io\/?p=71495"},"modified":"2024-10-29T15:11:50","modified_gmt":"2024-10-29T14:11:50","slug":"le-bon-samaritain","status":"publish","type":"post","link":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/","title":{"rendered":"Le bon Samaritain"},"content":{"rendered":"\n\n\t<section class=\"section\" id=\"section_177028554\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1990573620\">\n\n\n\t<div id=\"col-671618227\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3>J\u00e9sus veut nous enseigner la mis\u00e9ricorde<\/h3>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1682927521\">\n\n\n\t<div id=\"col-1602472702\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"lead\" style=\"font-weight: 400;\">&nbsp;<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71531 alignleft\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_poster-Jesus_Den_Barmhjertige_Samaritan2-711x400.jpg\" alt=\"\" width=\"500\" height=\"281\">Aimer notre prochain comme nous-m\u00eames signifie que nous nous soucions autant du bien-\u00eatre des autres que de notre propre bien-\u00eatre. Dans cette histoire, J\u00e9sus veut nous enseigner \u00e0 quel point il est important que nous soyons bons et attentionn\u00e9s envers ceux qui nous entourent. Et pas seulement envers ceux que nous aimons beaucoup, mais envers tout le monde. C&rsquo;est ce que J\u00e9sus veut que nous fassions.   <\/p>\n<p class=\"lead\" style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Ce th\u00e8me est quelque chose que les enfants du groupe cible peuvent facilement comprendre apr\u00e8s avoir vu le film. Parlez aux enfants de ce qu&rsquo;ils ont vu et laissez-les exprimer avec leurs propres mots ce qu&rsquo;ils ont appris de la parabole, ils la m\u00e9moriseront plus facilement et s&rsquo;en souviendront dans leur propre vie. <\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1179891238\">\n\n\n\t<div id=\"col-608693328\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3>\u00catre pr\u00eat \u00e0 aider les autres<\/h3>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1001488753\">\n\n\n\t<div id=\"col-2087283357\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"lead\" style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71561 alignright\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_poster-Jesus_Den_Barmhjertige_Samaritan4-711x400.jpg\" alt=\"\" width=\"500\" height=\"281\"><\/p>\n<p class=\"lead\" style=\"font-weight: 400;\">Dans le film, nous rencontrons Simon qui entend J\u00e9sus raconter la parabole du bon Samaritain. L\u2019histoire le passionne tellement qu&rsquo;il court \u00e0 la maison pour raconter ce qu&rsquo;il a entendu \u00e0 Sarah et \u00e0 sa m\u00e8re. <\/p>\n<p class=\"lead\" style=\"font-weight: 400;\">J\u00e9sus raconte l&rsquo;histoire d&rsquo;un homme juif en voyage, qui est soudain attaqu\u00e9 par des brigands et se retrouve \u00e0 demi mort sur le sol. Ensuite, un L\u00e9vite ainsi qu\u2019un pr\u00eatre arrivent sur les lieux.&nbsp; Ils \u00e9taient des personnes importantes \u00e0 l&rsquo;\u00e9poque, ils \u00e9taient cens\u00e9s savoir beaucoup de choses sur Dieu, mais aucun d&rsquo;eux ne s&rsquo;arr\u00eate pour aider l&rsquo;homme bless\u00e9. Finalement, un Samaritain arrive, et Simon sait que ces personnes ne sont pas tr\u00e8s amies avec les Juifs. Malgr\u00e9 cela, le Samaritain choisit de faire preuve de bont\u00e9 et de mis\u00e9ricorde. Il aide l&rsquo;homme, panse ses blessures et l&#8217;emm\u00e8ne dans un endroit o\u00f9 il peut rester jusqu&rsquo;\u00e0 son r\u00e9tablissement.&nbsp;    <\/p>\n<p class=\"lead\" style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71516 alignleft\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_poster-Jesus_Den_Barmhjertige_Samaritan-711x400.jpg\" alt=\"\" width=\"500\" height=\"281\">Les enfants peuvent faire de m\u00eame dans leur propre vie. Il s&rsquo;agit de voir les besoins des autres et d&rsquo;\u00eatre pr\u00eat \u00e0 aider celui qui en a besoin. Toi qui es mentor, peux-tu lancer une conversation avec les plus jeunes enfants \u00e0 ce sujet ? Les questions propos\u00e9es peuvent aider \u00e0 engager la conversation.  <\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-176978136\">\n\n\n\t<div id=\"col-503752495\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h4>Questions pour engager la conversation<\/h4>\n<p class=\"lead\">Savez-vous ce qu\u2019est la mis\u00e9ricorde ?<\/p>\n<p class=\"lead\">Qu\u2019est-ce que le Samaritain a fait de bien ?<\/p>\n<p class=\"lead\"><span style=\"font-weight: 400;\">Comment pouvons-nous faire preuve de mis\u00e9ricorde envers les autres ?<\/span><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1830363219\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h4>Chants convenant au th\u00e8me<\/h4>\n<p class=\"lead\">LBA 220 \u2013 \u00catre bon !<\/p>\n<p class=\"lead\">LBA 35 \u2013 La Bible nous raconte<\/p>\n<p class=\"lead\">LBA 203 \u2013 Je suis petit mais je veux<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1426696420\">\n\n\n\t<div id=\"col-588884340\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3>Versets bibliques convenant au th\u00e8me<\/h3>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1335944847\">\n\n\n\t<div id=\"col-1687111682\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<blockquote>\n<p style=\"font-weight: 400;\">Car toute la loi est accomplie dans une seule parole, dans celle-ci&nbsp; : <em>Tu aimeras ton prochain comme toi-m\u00eame.<\/em> &nbsp;Gal. 5, 14<\/p>\n<\/blockquote>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1245511614\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<blockquote>\n<p style=\"font-weight: 400;\">Tout ce que vous voulez que les hommes fassent pour vous, faites-le de m\u00eame pour eux. &nbsp;Matt. 7, 12<\/p>\n<\/blockquote>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1984787216\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<blockquote>\n<p style=\"font-weight: 400;\">Heureux les mis\u00e9ricordieux, &nbsp;car ils obtiendront mis\u00e9ricorde ! Matt. 5, 7 <\/p>\n<\/blockquote>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_177028554 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(247, 247, 247);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<p>Simon entend J\u00e9sus raconter la parabole du bon Samaritain et apprend comment J\u00e9sus pense que nous devrions traiter les gens.<\/p>\n","protected":false},"author":9614,"featured_media":72155,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"bcc_login_visibility":1,"bcc_groups":[],"bcc_groups_email":true,"bcc_visibility_groups":[],"bcc_visibility_groups_email":false,"sent_notifications":[],"footnotes":"","_links_to":"","_links_to_target":""},"categories":[176,132],"tags":[],"class_list":["post-71495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3-5-ans","category-pages-thematiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le bon Samaritain \u2013 Histoire biblique pour les petits<\/title>\n<meta name=\"description\" content=\"Simon entend J\u00e9sus raconter la parabole du bon Samaritain et apprend comment J\u00e9sus pense que nous devrions traiter les gens. Ressources pour l\u2019\u00e9cole du dimanche pour les petits enfants.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le bon Samaritain \u2013 Histoire biblique pour les petits\" \/>\n<meta property=\"og:description\" content=\"Simon entend J\u00e9sus raconter la parabole du bon Samaritain et apprend comment J\u00e9sus pense que nous devrions traiter les gens. Ressources pour l\u2019\u00e9cole du dimanche pour les petits enfants.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/\" \/>\n<meta property=\"og:site_name\" content=\"Bible Kids\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-15T12:26:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-29T14:11:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"15974\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"15974\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/le-bon-samaritain\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/le-bon-samaritain\\\/\"},\"author\":{\"name\":\"15974\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\"},\"headline\":\"Le bon Samaritain\",\"datePublished\":\"2023-05-15T12:26:54+00:00\",\"dateModified\":\"2024-10-29T14:11:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/le-bon-samaritain\\\/\"},\"wordCount\":542,\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/le-bon-samaritain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png\",\"articleSection\":[\"3-5 ans\",\"Pages th\u00e9matiques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/le-bon-samaritain\\\/\",\"url\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/le-bon-samaritain\\\/\",\"name\":\"Le bon Samaritain \u2013 Histoire biblique pour les petits\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/le-bon-samaritain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/le-bon-samaritain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png\",\"datePublished\":\"2023-05-15T12:26:54+00:00\",\"dateModified\":\"2024-10-29T14:11:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\"},\"description\":\"Simon entend J\u00e9sus raconter la parabole du bon Samaritain et apprend comment J\u00e9sus pense que nous devrions traiter les gens. Ressources pour l\u2019\u00e9cole du dimanche pour les petits enfants.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/le-bon-samaritain\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biblekids.io\\\/fr\\\/le-bon-samaritain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/le-bon-samaritain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png\",\"contentUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/le-bon-samaritain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/biblekids.io\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le bon Samaritain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\",\"url\":\"https:\\\/\\\/biblekids.io\\\/no\\\/\",\"name\":\"Bible Kids\",\"description\":\"Histoires bibliques pour enfants\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biblekids.io\\\/no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\",\"name\":\"15974\",\"url\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/author\\\/15974\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le bon Samaritain \u2013 Histoire biblique pour les petits","description":"Simon entend J\u00e9sus raconter la parabole du bon Samaritain et apprend comment J\u00e9sus pense que nous devrions traiter les gens. Ressources pour l\u2019\u00e9cole du dimanche pour les petits enfants.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/","og_locale":"fr_FR","og_type":"article","og_title":"Le bon Samaritain \u2013 Histoire biblique pour les petits","og_description":"Simon entend J\u00e9sus raconter la parabole du bon Samaritain et apprend comment J\u00e9sus pense que nous devrions traiter les gens. Ressources pour l\u2019\u00e9cole du dimanche pour les petits enfants.","og_url":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/","og_site_name":"Bible Kids","article_published_time":"2023-05-15T12:26:54+00:00","article_modified_time":"2024-10-29T14:11:50+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png","type":"image\/png"}],"author":"15974","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"15974","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/#article","isPartOf":{"@id":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/"},"author":{"name":"15974","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22"},"headline":"Le bon Samaritain","datePublished":"2023-05-15T12:26:54+00:00","dateModified":"2024-10-29T14:11:50+00:00","mainEntityOfPage":{"@id":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/"},"wordCount":542,"image":{"@id":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png","articleSection":["3-5 ans","Pages th\u00e9matiques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/","url":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/","name":"Le bon Samaritain \u2013 Histoire biblique pour les petits","isPartOf":{"@id":"https:\/\/biblekids.io\/no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/#primaryimage"},"image":{"@id":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png","datePublished":"2023-05-15T12:26:54+00:00","dateModified":"2024-10-29T14:11:50+00:00","author":{"@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22"},"description":"Simon entend J\u00e9sus raconter la parabole du bon Samaritain et apprend comment J\u00e9sus pense que nous devrions traiter les gens. Ressources pour l\u2019\u00e9cole du dimanche pour les petits enfants.","breadcrumb":{"@id":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biblekids.io\/fr\/le-bon-samaritain\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/#primaryimage","url":"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png","contentUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2023\/05\/SISA_S01_E08_Den_Barmhjertige_Samaritan.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/biblekids.io\/fr\/le-bon-samaritain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/biblekids.io\/ru\/"},{"@type":"ListItem","position":2,"name":"Le bon Samaritain"}]},{"@type":"WebSite","@id":"https:\/\/biblekids.io\/no\/#website","url":"https:\/\/biblekids.io\/no\/","name":"Bible Kids","description":"Histoires bibliques pour enfants","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biblekids.io\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22","name":"15974","url":"https:\/\/biblekids.io\/fr\/author\/15974\/"}]}},"_links":{"self":[{"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/posts\/71495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/users\/9614"}],"replies":[{"embeddable":true,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/comments?post=71495"}],"version-history":[{"count":7,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/posts\/71495\/revisions"}],"predecessor-version":[{"id":76594,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/posts\/71495\/revisions\/76594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/media\/72155"}],"wp:attachment":[{"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/media?parent=71495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/categories?post=71495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/tags?post=71495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}