{"id":98484,"date":"2024-04-04T15:18:29","date_gmt":"2024-04-04T13:18:29","guid":{"rendered":"https:\/\/biblekids.io\/?p=98484"},"modified":"2024-07-09T08:49:33","modified_gmt":"2024-07-09T06:49:33","slug":"on-peut-continuer-le-voyage-dans-le-temps-demain","status":"publish","type":"post","link":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/","title":{"rendered":"\u00a0\u00bb On peut continuer le voyage dans le temps demain ? \u00ab\u00a0"},"content":{"rendered":"\n\n\t<section class=\"section\" id=\"section_1376576770\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1371246333\">\n\n\n\t<div id=\"col-1868347724\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"lead\">\u00ab\u00a0C&rsquo;est tr\u00e8s motivant de voir que le concept int\u00e9resse les enfants\u00a0\u00bb, d\u00e9clare Annette, responsable de Bible Kids.<\/p>\n<p class=\"lead\">La semaine suivant P\u00e2ques, elle s&rsquo;est rendue \u00e0 Willingen, en Allemagne, pour le festival annuel de Spring, en compagnie de plusieurs repr\u00e9sentants de DCG Deutschland. Spring est un festival \u0153cum\u00e9nique chr\u00e9tien avec des ateliers et des s\u00e9minaires. Les participants sont invit\u00e9s \u00e0 pr\u00e9senter leurs concepts.<\/p>\n<p class=\"lead\">\u00ab\u00a0C&rsquo;\u00e9tait une excellente occasion pour nous de pr\u00e9senter notre concept de voyage dans le temps et de recevoir de pr\u00e9cieux retours \u00e0 ce sujet\u00a0\u00bb, explique Mme Tobler, qui trouve \u00e9galement beaucoup d&rsquo;inspiration \u00e0 l&rsquo;occasion de ce salon.<\/p>\n<p class=\"lead\">\u00a0\u00bb C&rsquo;est impressionnant de voir autant de personnes d\u00e9sireuses de transmettre le message chr\u00e9tien aux enfants \u00ab\u00a0, dit-elle. Tout au long de la semaine, Annette a guid\u00e9 plusieurs groupes d&rsquo;enfants \u00e0 travers le concept d&rsquo;exploration interactive de la Bible et a recueilli des r\u00e9actions positives de leur part.<\/p>\n<p class=\"lead\"><strong><em>\u00ab\u00a0Oups, il ne me reste plus qu&rsquo;une demi-minute dans le labyrinthe. C&rsquo;est tellement amusant !\u00a0\u00bb<\/em>, d\u00e9clare l&rsquo;un des enfants qui a particip\u00e9 \u00e0 l&rsquo;activit\u00e9.<\/strong><\/p>\n<h3 class=\"lead\" style=\"font-weight: 400;\"><strong>Un concept f\u00e9d\u00e9rateur<\/strong><\/h3>\n<p class=\"lead\" style=\"font-weight: 400;\">Annette a, pour l&rsquo;essentiel, test\u00e9 le concept avec des enfants de BCC, mais \u00e0 Spring, il y a des enfants de beaucoup d&rsquo;\u00e9glises diff\u00e9rentes. Annette a rassembl\u00e9 ces enfants en deux groupes : les 6-8 ans et les 9-11 ans. Tout le monde a pu vivre l&rsquo;int\u00e9gralit\u00e9 du voyage dans le temps sur Josias, en regardant les films et en accomplissant les t\u00e2ches. <\/p>\n<p class=\"lead\">&#8211;<span data-contrast=\"none\">\u00ab\u00a0C&rsquo;est formidable de voir que le concept fonctionne bien pour r\u00e9unir des enfants qui, au d\u00e9part, ne se connaissaient pas. En regardant les films et en r\u00e9alisant des t\u00e2ches ensemble, les enfants apprennent \u00e0 se conna\u00eetre <\/span><span data-contrast=\"none\">et ont v\u00e9cu une exp\u00e9rience en \u00e9quipe\u00a0\u00bb.<\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p class=\"lead\" style=\"font-weight: 400;\">Une fois le voyage termin\u00e9, les enfants ont re\u00e7u leur propre bo\u00eete biblique contenant des cartes bibliques li\u00e9es \u00e0 <a href=\"https:\/\/biblekids.io\/fr\/longs-metrages-bible-kids\/josias-vrai-et-juste\/\"><u>l&rsquo;histoire de Josias<\/u><\/a><\/p>\n<p class=\"lead\" style=\"font-weight: 400;\"><em><strong>\u00ab\u00a0Regarde maman, c&rsquo;est Glitch. Et \u00e7a, c&rsquo;est ma propre bo\u00eete \u00e0 tr\u00e9sors.\u00a0\u00bb<\/strong><\/em><\/p>\n<h3 class=\"lead\" style=\"font-weight: 400;\"><strong>Approche \u00e9ducative<\/strong><\/h3>\n<p class=\"lead\" style=\"font-weight: 400;\">Bible Kids Explorers est structur\u00e9 p\u00e9dagogiquement avec une probl\u00e9matique pr\u00e9sent\u00e9e au d\u00e9but, suivie par le r\u00e9cit d&rsquo;une histoire biblique avec diff\u00e9rents d\u00e9fis que les enfants doivent r\u00e9soudre pour progresser, et enfin, il se termine par un quiz r\u00e9sumant ce que les enfants ont appris. L&rsquo;ensemble du concept est consciemment con\u00e7u pour \u00eatre r\u00e9alis\u00e9 en groupe, avec un certain nombre d&rsquo;enfants collaborant et quelques adultes les guidant \u00e0 travers le programme. Annette a elle-m\u00eame une exp\u00e9rience dans le domaine de la p\u00e9dagogie et plusieurs ann\u00e9es d&rsquo;exp\u00e9rience dans l&rsquo;enseignement en milieu scolaire. <\/p>\n<p class=\"lead\">\u00ab\u00a0Il est particuli\u00e8rement int\u00e9ressant de voir les enfants \u00e9prouver un sentiment de r\u00e9ussite, de savoir qu&rsquo;ils peuvent r\u00e9pondre aux questions \u00e0 la fin\u00a0\u00bb, d\u00e9clare Annette.<\/p>\n<p class=\"lead\" style=\"font-weight: 400;\">En savoir plus sur le concept de voyage dans le temps <a href=\"https:\/\/biblekids.io\/fr\/bible-kids-explorers\/\"><u>ici.<\/u><\/a><\/p>\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/biblekids.io\/wp-content\/uploads\/2024\/04\/photo_2024-04-04-14.58.03-600x800.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2024\/04\/photo_2024-04-04-14.58.03-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"93052,93082,93067\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/biblekids.io\/wp-content\/uploads\/2024\/04\/photo_2024-04-04-14.58.13-600x800.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2024\/04\/photo_2024-04-04-14.58.13-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"93052,93082,93067\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/biblekids.io\/wp-content\/uploads\/2024\/04\/photo_2024-04-04-14.58.09-600x800.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-overlay dark\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"400\" src=\"https:\/\/biblekids.io\/wp-content\/uploads\/2024\/04\/photo_2024-04-04-14.58.09-300x400.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"93052,93082,93067\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0,0,0,.15)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\n<div class=\"row\"  id=\"row-1739302388\">\n\n\n\t<div id=\"col-660319769\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-594594760\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-594594760 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1376576770 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est ce qu&rsquo;a dit l&rsquo;un des enfants qui, cette semaine, a \u00e9t\u00e9 invit\u00e9 \u00e0 tester Bible Kids Explorers avec Annette Tobler au Christian Spring Festival en Allemagne.<\/p>\n","protected":false},"author":9614,"featured_media":93098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"bcc_login_visibility":1,"bcc_groups":[],"bcc_groups_email":true,"bcc_visibility_groups":[],"bcc_visibility_groups_email":false,"sent_notifications":[],"footnotes":"","_links_to":"","_links_to_target":""},"categories":[143],"tags":[],"class_list":["post-98484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspiration-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot; On peut continuer le voyage dans le temps demain ? &quot; - Bible Kids<\/title>\n<meta name=\"description\" content=\"Le concept Bible Kids Explorers est test\u00e9 lors du festival Christian Spring en Allemagne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot; On peut continuer le voyage dans le temps demain ? &quot; - Bible Kids\" \/>\n<meta property=\"og:description\" content=\"Le concept Bible Kids Explorers est test\u00e9 lors du festival Christian Spring en Allemagne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/\" \/>\n<meta property=\"og:site_name\" content=\"Bible Kids\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-04T13:18:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-09T06:49:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biblekids.io\/wp-content\/uploads\/2024\/04\/photo_2024-04-04-14.57.58.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"15974\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"15974\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/on-peut-continuer-le-voyage-dans-le-temps-demain\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/on-peut-continuer-le-voyage-dans-le-temps-demain\\\/\"},\"author\":{\"name\":\"15974\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\"},\"headline\":\"\u00a0\u00bb On peut continuer le voyage dans le temps demain ? \u00ab\u00a0\",\"datePublished\":\"2024-04-04T13:18:29+00:00\",\"dateModified\":\"2024-07-09T06:49:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/on-peut-continuer-le-voyage-dans-le-temps-demain\\\/\"},\"wordCount\":541,\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/on-peut-continuer-le-voyage-dans-le-temps-demain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/photo_2024-04-04-14.57.58.jpeg\",\"articleSection\":[\"Inspiration\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/on-peut-continuer-le-voyage-dans-le-temps-demain\\\/\",\"url\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/on-peut-continuer-le-voyage-dans-le-temps-demain\\\/\",\"name\":\"\\\" On peut continuer le voyage dans le temps demain ? \\\" - Bible Kids\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/on-peut-continuer-le-voyage-dans-le-temps-demain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/on-peut-continuer-le-voyage-dans-le-temps-demain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/photo_2024-04-04-14.57.58.jpeg\",\"datePublished\":\"2024-04-04T13:18:29+00:00\",\"dateModified\":\"2024-07-09T06:49:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\"},\"description\":\"Le concept Bible Kids Explorers est test\u00e9 lors du festival Christian Spring en Allemagne.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/on-peut-continuer-le-voyage-dans-le-temps-demain\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biblekids.io\\\/fr\\\/on-peut-continuer-le-voyage-dans-le-temps-demain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/on-peut-continuer-le-voyage-dans-le-temps-demain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/photo_2024-04-04-14.57.58.jpeg\",\"contentUrl\":\"https:\\\/\\\/biblekids.io\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/photo_2024-04-04-14.57.58.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/on-peut-continuer-le-voyage-dans-le-temps-demain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/biblekids.io\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a0\u00bb On peut continuer le voyage dans le temps demain ? \u00ab\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#website\",\"url\":\"https:\\\/\\\/biblekids.io\\\/no\\\/\",\"name\":\"Bible Kids\",\"description\":\"Histoires bibliques pour enfants\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biblekids.io\\\/no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biblekids.io\\\/no\\\/#\\\/schema\\\/person\\\/ae014485a07253d1fc2a399d0bc7bf22\",\"name\":\"15974\",\"url\":\"https:\\\/\\\/biblekids.io\\\/fr\\\/author\\\/15974\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\" On peut continuer le voyage dans le temps demain ? \" - Bible Kids","description":"Le concept Bible Kids Explorers est test\u00e9 lors du festival Christian Spring en Allemagne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/","og_locale":"fr_FR","og_type":"article","og_title":"\" On peut continuer le voyage dans le temps demain ? \" - Bible Kids","og_description":"Le concept Bible Kids Explorers est test\u00e9 lors du festival Christian Spring en Allemagne.","og_url":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/","og_site_name":"Bible Kids","article_published_time":"2024-04-04T13:18:29+00:00","article_modified_time":"2024-07-09T06:49:33+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/biblekids.io\/wp-content\/uploads\/2024\/04\/photo_2024-04-04-14.57.58.jpeg","type":"image\/jpeg"}],"author":"15974","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"15974","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/#article","isPartOf":{"@id":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/"},"author":{"name":"15974","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22"},"headline":"\u00a0\u00bb On peut continuer le voyage dans le temps demain ? \u00ab\u00a0","datePublished":"2024-04-04T13:18:29+00:00","dateModified":"2024-07-09T06:49:33+00:00","mainEntityOfPage":{"@id":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/"},"wordCount":541,"image":{"@id":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2024\/04\/photo_2024-04-04-14.57.58.jpeg","articleSection":["Inspiration"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/","url":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/","name":"\" On peut continuer le voyage dans le temps demain ? \" - Bible Kids","isPartOf":{"@id":"https:\/\/biblekids.io\/no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/#primaryimage"},"image":{"@id":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/#primaryimage"},"thumbnailUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2024\/04\/photo_2024-04-04-14.57.58.jpeg","datePublished":"2024-04-04T13:18:29+00:00","dateModified":"2024-07-09T06:49:33+00:00","author":{"@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22"},"description":"Le concept Bible Kids Explorers est test\u00e9 lors du festival Christian Spring en Allemagne.","breadcrumb":{"@id":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/#primaryimage","url":"https:\/\/biblekids.io\/wp-content\/uploads\/2024\/04\/photo_2024-04-04-14.57.58.jpeg","contentUrl":"https:\/\/biblekids.io\/wp-content\/uploads\/2024\/04\/photo_2024-04-04-14.57.58.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/biblekids.io\/fr\/on-peut-continuer-le-voyage-dans-le-temps-demain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/biblekids.io\/ru\/"},{"@type":"ListItem","position":2,"name":"\u00a0\u00bb On peut continuer le voyage dans le temps demain ? \u00ab\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/biblekids.io\/no\/#website","url":"https:\/\/biblekids.io\/no\/","name":"Bible Kids","description":"Histoires bibliques pour enfants","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biblekids.io\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/biblekids.io\/no\/#\/schema\/person\/ae014485a07253d1fc2a399d0bc7bf22","name":"15974","url":"https:\/\/biblekids.io\/fr\/author\/15974\/"}]}},"_links":{"self":[{"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/posts\/98484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/users\/9614"}],"replies":[{"embeddable":true,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/comments?post=98484"}],"version-history":[{"count":3,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/posts\/98484\/revisions"}],"predecessor-version":[{"id":100150,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/posts\/98484\/revisions\/100150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/media\/93098"}],"wp:attachment":[{"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/media?parent=98484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/categories?post=98484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biblekids.io\/fr\/wp-json\/wp\/v2\/tags?post=98484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}